{"id":1963,"date":"2025-11-15T11:07:08","date_gmt":"2025-11-15T16:07:08","guid":{"rendered":"https:\/\/megafoniando.cerrosfc.org\/?p=1963"},"modified":"2025-11-15T11:07:09","modified_gmt":"2025-11-15T16:07:09","slug":"cerros-fc-llena-de-magia-y-sonrisas-la-cancha-cubierta-de-los-cerros-con-su-fiesta-de-halloween","status":"publish","type":"post","link":"https:\/\/megafoniando.cerrosfc.org\/index.php\/2025\/11\/15\/cerros-fc-llena-de-magia-y-sonrisas-la-cancha-cubierta-de-los-cerros-con-su-fiesta-de-halloween\/","title":{"rendered":"Cerros FC llena de magia y sonrisas la cancha cubierta de Los Cerros con su fiesta de Halloween"},"content":{"rendered":"\n<p>La <strong>Corporaci\u00f3n Sociocultural Cerros FC<\/strong> nuevamente demostr\u00f3 su compromiso con la comunidad al realizar una fiesta de Halloween que ilumin\u00f3 la cancha cubierta de Los Cerros con colores, disfraces y mucha alegr\u00eda. El evento, pensado especialmente para ni\u00f1os, ni\u00f1as y j\u00f3venes del sector, se convirti\u00f3 en un espacio seguro y creativo donde la imaginaci\u00f3n fue la protagonista.<\/p>\n\n\n\n<p>Durante la jornada, los participantes disfrutaron de actividades l\u00fadicas, concursos, m\u00fasica y din\u00e1micas que promovieron la integraci\u00f3n y el trabajo en equipo. M\u00e1s que una celebraci\u00f3n, la fiesta busc\u00f3 fortalecer los v\u00ednculos comunitarios y brindar un momento de esparcimiento en el que cada ni\u00f1o pudiera expresarse libremente a trav\u00e9s del juego y el arte.<\/p>\n\n\n\n<p>Esta iniciativa no solo resalt\u00f3 la importancia de generar espacios de convivencia y diversi\u00f3n, sino que reafirm\u00f3 el rol de Cerros FC como un actor sociocultural comprometido con el bienestar y la formaci\u00f3n integral de la ni\u00f1ez y la juventud de la Comuna 9. Cada sonrisa, disfraz y actividad dej\u00f3 huella, convirtiendo esta fiesta en una experiencia significativa para toda la comunidad.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Fiesta de Halloween Cerros FC \" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/NXc2drq16oQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Corporaci\u00f3n Sociocultural Cerros FC nuevamente demostr\u00f3 su compromiso con la comunidad al realizar una fiesta de Halloween que ilumin\u00f3 la cancha cubierta de Los Cerros con colores, disfraces y mucha alegr\u00eda. El evento, pensado especialmente para ni\u00f1os, ni\u00f1as y j\u00f3venes del sector, se convirti\u00f3 en un espacio seguro y creativo donde la imaginaci\u00f3n fue la protagonista. Durante la jornada, los participantes disfrutaron de actividades l\u00fadicas, concursos, m\u00fasica y din\u00e1micas que promovieron la integraci\u00f3n y el trabajo en equipo. M\u00e1s que una celebraci\u00f3n, la fiesta busc\u00f3 fortalecer los v\u00ednculos comunitarios y brindar un momento de esparcimiento en el que cada ni\u00f1o pudiera expresarse libremente a trav\u00e9s del juego y el arte. Esta iniciativa no solo resalt\u00f3 la importancia de generar espacios de convivencia y diversi\u00f3n, sino que reafirm\u00f3 el rol de Cerros FC como un actor sociocultural comprometido con el bienestar y la formaci\u00f3n integral de la ni\u00f1ez y la juventud de la Comuna 9. Cada sonrisa, disfraz y actividad dej\u00f3 huella, convirtiendo esta fiesta en una experiencia significativa para toda la comunidad.<\/p>\n","protected":false},"author":1,"featured_media":1964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":4,"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/posts\/1963"}],"collection":[{"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/comments?post=1963"}],"version-history":[{"count":1,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/posts\/1963\/revisions"}],"predecessor-version":[{"id":1965,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/posts\/1963\/revisions\/1965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/media\/1964"}],"wp:attachment":[{"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/media?parent=1963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/categories?post=1963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megafoniando.cerrosfc.org\/index.php\/wp-json\/wp\/v2\/tags?post=1963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}